{"id":83,"date":"2013-04-06T15:53:41","date_gmt":"2013-04-06T21:53:41","guid":{"rendered":"http:\/\/www.remhi.org.gt\/portal\/?p=83"},"modified":"2024-09-13T17:26:14","modified_gmt":"2024-09-13T23:26:14","slug":"metodologia-de-investigacion","status":"publish","type":"post","link":"https:\/\/www.remhi.org.gt\/portal\/metodologia-de-investigacion\/","title":{"rendered":"Metodolog\u00eda de investigaci\u00f3n"},"content":{"rendered":"<h2>Informe elaborado por Carlos Mart\u00edn Beristain, coordinador del Informe Guatemala Nunca M\u00e1s.<\/h2>\n<p>&nbsp;<\/p>\n<p><b>El Proyecto REMHI<\/b><\/p>\n<p>En 1995, dos a\u00f1os antes de la firma de los Acuerdos de Paz entre el gobierno de Guatemala y la URNG, la Oficina de Derechos Humanos del Arzobispado (ODHAG) inici\u00f3 un proyecto para recoger testimonios sobre las violaciones de los derechos humanos en Guatemala. Durante muchos a\u00f1os los familiares y sobrevivientes no pudieron compartir su experiencia, dar a conocer lo sucedido o denunciar a los responsables.<\/p>\n<p>Para ello, el objetivo inicial de este proyecto era dar insumos a la futura Comisi\u00f3n para el Esclarecimiento Hist\u00f3rico (CEH) cuyo acuerdo b\u00e1sico hab\u00eda sido ya logrado sobre el papel en las negociaciones entre el gobierno y la guerrilla. El proyecto REMHI quer\u00eda, en un principio, avanzar en el trabajo que posteriormente tendr\u00eda que hacer la CEH contribuyendo a hacer su trabajo m\u00e1s eficaz en un pa\u00eds multicultural y pluriling\u00fce.<\/p>\n<p>El inicio de esta experiencia de REMHI fue asumido por varias di\u00f3cesis de la Iglesia cat\u00f3lica, que se comprometieron a impulsar el trabajo en distintos departamentos. Adem\u00e1s de la ODHAG, las di\u00f3cesis que m\u00e1s impulsaron el proyecto fueron las de Quich\u00e9, Alta y Baja Verapaz, Huehuetenango, Pet\u00e9n, San Marcos y Quetzaltenango. En Izabal se realiz\u00f3 un gran trabajo en algunas zonas m\u00e1s afectadas como El Estor. En menor medida se realiz\u00f3 en lugares como Chimaltenango, Escuintla o Solol\u00e1. El proyecto tuvo escasa incidencia en regiones del sur oriente como Zacapa y Jalapa m\u00e1s golpeadas por la violencia en los a\u00f1os 60 pero en menor medida en la d\u00e9cada de los 80 (este \u00faltimo constituy\u00f3 el periodo central de la violencia contrainsurgente denominado habitualmente \u201ctierra arrasada\u201d).<\/p>\n<p>El Proyecto REMHI part\u00eda de una situaci\u00f3n distinta a otras experiencias como Comisiones de la Verdad que se realizaron en contextos en los que la tensi\u00f3n pol\u00edtica y las amenazas hab\u00edan disminuido. En este caso, a pesar de la mejora del clima de miedo en los \u00faltimos tiempos, la permanencia del poder militar, y la actuaci\u00f3n de grupos paramilitares, en el \u00e1rea rural hac\u00edan de este esfuerzo una experiencia dif\u00edcil que ten\u00eda que enfrentarse al mantenimiento de las presiones y amenazas contra la poblaci\u00f3n que pod\u00eda dar su testimonio.<\/p>\n<p>El tiempo de investigaci\u00f3n, desde la preparaci\u00f3n del proyecto, selecci\u00f3n y entrenamiento de entrevistadores, organizaci\u00f3n y desarrollo del trabajo de campo, codificaci\u00f3n y estudio de los testimonios hasta la elaboraci\u00f3n y publicaci\u00f3n del informe Guatemala Nunca M\u00e1s, fue de 3 a\u00f1os (1995-1998). S\u00f3lo el trabajo de campo, la recogida de testimonios en las diferentes regiones del pa\u00eds, dur\u00f3 aproximadamente un a\u00f1o con lo que\u00a0 se realiz\u00f3 de manera extensa y llegando a obtener una muestra muy importante de testimonios (m\u00e1s de cinco mil).<\/p>\n<h4>Selecci\u00f3n y capacitaci\u00f3n de entrevistadores<\/h4>\n<p>Los entrevistadores (<i>animadores<\/i>) fueron gente de las propias comunidades. Eso facilit\u00f3 la accesibilidad y la confianza de la gente, y un sentido de reconstrucci\u00f3n del tejido social. Pero tambi\u00e9n pod\u00eda traer sus problemas, como compaginar la investigaci\u00f3n de los hechos y el apoyo a la v\u00edctima, no inducir respuestas, etc. La formaci\u00f3n se convirti\u00f3 en un elemento clave para capacitar a los entrevistadores \u2013en total unos 600 personas- en la recogida de testimonios y la necesidad de afrontar numerosos problemas t\u00e9cnicos y organizativos. En cada regi\u00f3n el ritmo fue distinto, pero, una vez iniciado, ese proceso de formaci\u00f3n previsto llev\u00f3 de cuatro a seis meses y se realiz\u00f3 de una manera sistem\u00e1tica.<\/p>\n<p>Los entrevistadores fueron seleccionados por representantes de las comunidades y sectores religiosos que contaban con la confianza de la gente. Entre los criterios de selecci\u00f3n estaban: capacidad de escucha y comunicaci\u00f3n; confianza y reconocimiento de la gente de la comunidad; compromiso de confidencialidad y continuidad en el trabajo. Durante el periodo de recogida de testimonios se realizaron actividades de seguimiento, tales como talleres y encuentros que fueron importantes para unificar criterios. Los entrevistadores contaron con una acreditaci\u00f3n otorgada por el obispo de su di\u00f3cesis para poder ser reconocidos por la gente o presentarse ante las autoridades.<\/p>\n<p>De acuerdo a un proceso de investigaci\u00f3n-acci\u00f3n, y al propio car\u00e1cter comunitario de la cultura maya, el trabajo con los entrevistadores se convirti\u00f3 tambi\u00e9n en un espacio para un mayor conocimiento de los efectos de la violencia, las dificultades pr\u00e1cticas para la recogida de testimonios o las formas de enfrentar el miedo. B\u00e1sicamente los pasos de esas capacitaciones<a title=\"\" href=\"#_ftn1\">[1]<\/a> fueron: 1) presentaci\u00f3n y sentido del proyecto. 2) para qu\u00e9 sirve la historia 3) los efectos\u00a0 de la violencia 4) afrontar el miedo 5) el valor del testimonio 6) el manejo de las preguntas en la entrevista 7) los problemas en la conducci\u00f3n de la entrevista 8) uso de instrumentos y sistematizaci\u00f3n.<\/p>\n<h4>La sistematizaci\u00f3n de las entrevistas<\/h4>\n<p>Para facilitar la comparabilidad de los testimonios y la conducci\u00f3n de las entrevistas se estructur\u00f3 una metodolog\u00eda basada en siete preguntas para la recogida de testimonios: \u00bfqu\u00e9 sucedi\u00f3?, \u00bfcuando y d\u00f3nde?, \u00bfquienes fueron los responsables?, \u00bfqu\u00e9 efectos tuvo ese hecho en su vida?, \u00bfqu\u00e9 hizo para enfrentarlo?, \u00bfpor qu\u00e9 cree que pas\u00f3? y \u00bfqu\u00e9 habr\u00eda que hacer para que no volviera a suceder?.<\/p>\n<p>Esas preguntas trataban de recoger el conjunto de la experiencia. Algunas hac\u00edan referencia a los hechos, otras a la experiencia subjetiva y las consecuencias de la violencia, a la postura activa de los sobrevivientes, al significado que le daban a los hechos, a sus demandas y esperanzas.<\/p>\n<p>Las entrevistas fueron grabadas. A pesar de los fuertes debates y los problemas iniciales para efectuar la grabaci\u00f3n de los testimonios (interferencia en la comunicaci\u00f3n y riesgo percibido por la persona declarante), \u00e9ste fue un aspecto clave para la siguiente fase de an\u00e1lisis y documentaci\u00f3n de las violaciones. La grabaci\u00f3n y la transcripci\u00f3n posterior de testimonios han permitido un an\u00e1lisis m\u00e1s fidedigno y mantienen las voces de la gente para futuras investigaciones.<\/p>\n<p>Los entrevistadores rellenaron varias fichas de cada testimonio, en las que se vaciaba la informaci\u00f3n m\u00e1s significativa incluyendo: 1) ficha del declarante. 2) ficha de la v\u00edctima. 3) ficha del responsable o autor del hecho. Adem\u00e1s se inclu\u00eda un resumen de la entrevista y en muchos casos la transcripci\u00f3n completa de la misma.\u00a0 Todos esta informaci\u00f3n fue incluida en la base de datos del Proyecto REMHI, en la Oficina de Derechos Humanos del Arzobispado de Guatemala.<\/p>\n<h4>Coordinaci\u00f3n del trabajo de campo<\/h4>\n<p>El gran n\u00famero de testimonios recogidos y la dispersi\u00f3n geogr\u00e1fica hizo necesario establecer formas de coordinaci\u00f3n locales y de \u00e1mbito nacional. En el nivel local (regi\u00f3n, di\u00f3cesis) se coordin\u00f3 la recogida de los testimonios, la revisi\u00f3n de la documentaci\u00f3n y grabaciones, la traducci\u00f3n y transcripci\u00f3n de algunos testimonios y realizaci\u00f3n de un resumen. En el nivel central se recog\u00edan los testimonios enviados, se analizaban los res\u00famenes y la calidad de la informaci\u00f3n, se tomaban decisiones sobre la transcripci\u00f3n de algunos testimonios (en total, uno de cada cinco fueron transcritos) y se coordinaba la codificaci\u00f3n y la base de datos que se iba a utilizar para el an\u00e1lisis.<\/p>\n<h4>Equipo de coordinaci\u00f3n<\/h4>\n<p>La informaci\u00f3n de cada di\u00f3cesis se centraliz\u00f3 en las diferentes regiones del pa\u00eds. Los coordinadores locales organizaron oficinas y equipos regionales donde se guard\u00f3 la informaci\u00f3n, se realizaron las traducciones de numerosos testimonios y se comprobaron los datos rellenados en las fichas por los entrevistadores. Los equipos de coordinaci\u00f3n estaban formados por cerca de treinta personas de confianza de las distintas di\u00f3cesis. Mensualmente se realizaron reuniones de coordinaci\u00f3n general de las distintas di\u00f3cesis y partes del proyecto para reajustar la metodolog\u00eda, estudiar algunos temas y establecer los planes de trabajo.<\/p>\n<h4>Equipos de investigaci\u00f3n<\/h4>\n<p>La informaci\u00f3n recogida en cada di\u00f3cesis fue enviada posteriormente a la ODHAG donde se codificaban los testimonios, se insertaban en la base de datos para estar disponibles para el equipo de investigadores.\u00a0 Se estructuraron cinco equipos de investigaci\u00f3n sobre las diferentes tem\u00e1ticas y enfoques del informe (psicosocial, cultural, g\u00e9nero, jur\u00eddico, y sociohist\u00f3rico).<\/p>\n<p>Dichos equipos contaron en total con 21 personas con conocimiento de la problem\u00e1tica de la violencia en Guatemala, capacidad de sistematizaci\u00f3n y experiencia reconocida. Se realizaron reuniones de coordinaci\u00f3n mensuales y un seguimiento de su trabajo m\u00e1s directo llevado a cabo por el coordinador del informe.<\/p>\n<h4>Codificaci\u00f3n y base de datos<\/h4>\n<p>En base a una primera escucha de cincuenta testimonios, realizada por tres investigadores distintos de forma simult\u00e1nea se estructur\u00f3 un<i> tesauro<a title=\"\" href=\"#_ftn2\"><b>[2]<\/b><\/a><\/i> con 250 categor\u00edas de an\u00e1lisis respecto a caracter\u00edsticas de los hechos, actores implicados, consecuencias, formas de afrontamiento, causas percibidas, as\u00ed como demandas de la gente. La versi\u00f3n completa de esa gu\u00eda fue manejada en el an\u00e1lisis de los 5180 testimonios recogidos.<\/p>\n<p>Todo ese trabajo supuso una compleja din\u00e1mica de selecci\u00f3n y formaci\u00f3n de un grupo de codificadores. Estos codificadores fueron personas capacitadas para la escucha, transcripci\u00f3n e identificaci\u00f3n de los distintos aspectos del tesauro construido. En nuestra experiencia fue muy importante el trabajo de discusi\u00f3n de casos y asesoramiento permanente a este grupo de codificadores, que se convirtieron a su vez en una fuente de informaci\u00f3n muy valiosa para las personas responsables del an\u00e1lisis. Semanalmente se discutieron con los codificadores los problemas que aparec\u00edan para asegurar que los criterios eran compartidos y evitar los sesgos. Se estableci\u00f3 adem\u00e1s un sistema permanente de consultas con el responsable de investigaci\u00f3n sobre los casos dudosos.<\/p>\n<h4>An\u00e1lisis de los sesgos<\/h4>\n<p>Reconstruir una historia tan amplia y compleja desde las voces de las v\u00edctimas era parte del sentido de nuestro trabajo, pero tambi\u00e9n un l\u00edmite del mismo. El valor y los l\u00edmites en el uso del testimonio para la reconstrucci\u00f3n de la experiencia y de la historia, han sido investigados especialmente por la historia oral y la psicolog\u00eda social<a title=\"\" href=\"#_ftn3\">[3]<\/a>.<\/p>\n<p>Entre los factores que en nuestra experiencia fueron importantes para caracterizar ese valor del testimonio se encontraban: 1) el tiempo desde que sucedieron los hechos (fiabilidad de fechas). 2) el impacto traum\u00e1tico de la violencia y sus posibles consecuencias en la focalizaci\u00f3n del recuerdo, olvido selectivo, etc. 3) la valoraci\u00f3n supuesta del entrevistador respecto a la violencia o la participaci\u00f3n pol\u00edtica (por ejemplo, dif\u00edcil reconocer el papel de la guerrilla en una situaci\u00f3n todav\u00eda de incertidumbre, o se\u00f1alar responsables que siguen viviendo en sus comunidades, etc.) 4) los procesos del recuerdo (simplificaci\u00f3n; amplificaci\u00f3n de algunos hechos; versi\u00f3n convencionalizada adaptada a las necesidades del presente) que pod\u00edan hacer aparecer algunos t\u00f3picos, especialmente matizados por una memoria \u201cdel vencido\u201d. 5) la cultura subjetiva, especialmente la concepci\u00f3n del tiempo circular (encadenamiento de sucesos, por ejemplo) o las formas de expresi\u00f3n propias (las expresiones sobre \u201cel tiempo de la violencia\u201d, el concepto de envidia en las sociedades tradicionales, etc.).<\/p>\n<p>Las pruebas b\u00e1sicas de fiabilidad que se tuvieron en cuenta fueron: investigar la coherencia interna del testimonio, los fundamentos del hecho que le constaban al declarante; contrastar y comprobar detalles a partir de otras fuentes; sopesar la evidencia en un contexto m\u00e1s amplio.<\/p>\n<p>Adem\u00e1s, se usaron procedimientos de triangulaci\u00f3n de las fuentes y\/o los m\u00e9todos, con objeto de realizar un contraste m\u00e1s sistem\u00e1tico y evitar los sesgos propios de cada m\u00e9todo o fuente ( para ello se utilizaron diferentes fuentes tal y como se recoge posteriormente en el ep\u00edgrafe: Fuentes de informaci\u00f3n).<\/p>\n<h4>Criterios para la obtenci\u00f3n de testimonios<\/h4>\n<p>Los testimonios fueron aportados voluntariamente por parte de los sobrevivientes, los familiares de las v\u00edctimas y testigos directos de los hechos. Los testimonios fueron grabados para asegurar su fiabilidad y posibilidad de contrastar los resultados, as\u00ed como se comprob\u00f3 la identidad de los declarantes, cuya confidencialidad fue asegurada por el Proyecto REMHI. En algunos casos el Proyecto REMHI busc\u00f3 algunos testigos o informantes clave proponi\u00e9ndoles la posibilidad de dar su testimonios para completar o contrastar los datos recabados.<\/p>\n<p><b>Estructuraci\u00f3n del an\u00e1lisis y del Informe<\/b><\/p>\n<p>El Informe final\u00a0 Guatemala, Nunca M\u00e1s consta de cuatro tomos (1,400 p\u00e1ginas) que abordan estos temas: 1) Los impactos individuales, familiares y comunitarios de la violencia, las formas de supervivencia y las demandas de las v\u00edctimas. 2) Los mecanismos del horror (c\u00f3mo se cometieron las masacres, las torturas; los m\u00e9todos que emplearon los aparatos de inteligencia y las fuerzas insurgentes y contrainsurgentes contra la poblaci\u00f3n). 3) El entorno hist\u00f3rico (el proceso pol\u00edtico, econ\u00f3mico y militar desde los a\u00f1os 50 hasta la firma de la paz). 4) Las v\u00edctimas del conflicto (nombres de v\u00edctimas de las masacres, muertos, desaparecidos y torturados) y las estad\u00edsticas generales de violaciones de los Derechos Humanos y del Derecho Internacional Humanitario, as\u00ed como las Recomendaciones del Proyecto REMHI.<\/p>\n<h4>Fuentes de informaci\u00f3n y tratamiento de los datos<\/h4>\n<p>A continuaci\u00f3n se refieren las diferentes fuentes de informaci\u00f3n utilizadas para la investigaci\u00f3n del proyecto REMHI y la elaboraci\u00f3n del Informe Guatemala Nunca M\u00e1s.<\/p>\n<p>1)\u00a0\u00a0\u00a0 Los 5180 <i>testimonios de v\u00edctimas y sobrevivientes<\/i> recogidos (ver los ep\u00edgrafes siguientes sobre an\u00e1lisis cualitativo y cuantitativo en el an\u00e1lisis de los testimonios).<\/p>\n<p>2)\u00a0\u00a0\u00a0 <i>Estudios de caso<\/i>. Se encargaron doce estudios espec\u00edficos a otros tantos investigadores independientes sobre problem\u00e1ticas como la violencia en determinadas \u00e1reas (como el \u00e1rea Ixil en los a\u00f1os 80; y las masacres del Ixc\u00e1n), hechos de violencia espec\u00edficos (como el caso de los estudiantes de la USAC en 1989), el nacimiento de la guerrilla o las v\u00edctimas de la Iglesia Cat\u00f3lica (como el caso de los sacerdotes y monjas asesinados). Estos estudios constituyeron insumos b\u00e1sicos para completar el an\u00e1lisis hist\u00f3rico recogidos en el Tomo III del informe (Entorno Hist\u00f3rico)<\/p>\n<p>3)\u00a0\u00a0\u00a0 Entrevistas a <i>testigos clave<\/i>. Se realizaron m\u00e1s de doscientas entrevistas con personas que ofrecieron informaci\u00f3n significativa por haber sido testigos directos o participado en diferentes acontecimientos (diplom\u00e1ticos, miembros de organizaciones sociales, instituciones, testigos de hechos hist\u00f3ricos, exmiembros de la URNG, etc.).<\/p>\n<p>4)\u00a0\u00a0\u00a0 <i>Revisi\u00f3n bibliogr\u00e1fica<\/i>. Especialmente para la documentaci\u00f3n incluida en el tomo III relativa al Entorno Hist\u00f3rico y la evoluci\u00f3n de los acontecimientos durante los 36 a\u00f1os de guerra. La documentaci\u00f3n analizada se encuentra disponible en la bibliograf\u00eda rese\u00f1ada en el tomo III.<\/p>\n<p>5)\u00a0\u00a0\u00a0 <i>Diagn\u00f3sticos comunitarios<\/i>. Se realizaron m\u00e1s de 100 an\u00e1lisis de pueblos o aldeas significativas, a partir de entrevistas comunitarias y talleres en donde se recogi\u00f3 informaci\u00f3n sobre la situaci\u00f3n antes de la violencia, los hechos vividos y la situaci\u00f3n posterior. Dichos diagn\u00f3sticos sirvieron para hacer mapas como los incluidos en el tomo III relativos a masacres, presencia de las PAC y presencia de organizaciones guerrilleras.<\/p>\n<p>6)\u00a0\u00a0\u00a0 <i>Revisi\u00f3n hemerogr\u00e1fica<\/i>. Se realiz\u00f3 una revisi\u00f3n de los hechos de violencia en diferentes periodos hist\u00f3ricos para completar la informaci\u00f3n o los datos de muchos casos registrados y tambi\u00e9n para la descripci\u00f3n cronol\u00f3gica del entorno hist\u00f3rico (Tomo III)<\/p>\n<p>7)\u00a0\u00a0\u00a0 <i>Monograf\u00edas<\/i>. Del mismo modo que los estudios de caso, se realizaron una decena de monograf\u00edas sobre aspectos m\u00e1s transversales de actores sociales respecto a los cuales no se encontraba informaci\u00f3n espec\u00edfica como por ejemplo el papel de los empresarios, la dimensi\u00f3n socioecon\u00f3mica, el papel de la Iglesia y la inteligencia militar, entre otros. Como en el caso de los estudios de caso, estas monograf\u00edas fueron encargadas a personas con experiencia y con una independencia de criterios respecto a tendencias pol\u00edticas de los actores armados.<\/p>\n<p>8)\u00a0\u00a0\u00a0 <i>Entrevistas colectivas<\/i>. En varias ocasiones se utilizaron entrevistas colectivas, especialmente cuando los hechos investigados hab\u00edan sido vividos colectivamente. Por ejemplo, en algunos casos de masacres del Ixc\u00e1n y en el caso de la Aldea Modelo de Akamal.<\/p>\n<p>9)\u00a0\u00a0\u00a0 <i>Testimonios de perpetradores<\/i>. Algunas personas que declararon como v\u00edctimas y testigos de violencia, hab\u00edan a su vez participado como perpetradores. Esto se dio especialmente en el caso de patrulleros civiles que relataron ser obligados a participar en asesinatos o masacres. Sin embargo, tambi\u00e9n se recogieron cerca de 30 testimonios de miembros del ej\u00e9rcito y los servicios de inteligencia que dieron detalles muy concretos sobre operaciones, preparaci\u00f3n y entrenamiento militar, as\u00ed como el impacto psicol\u00f3gico de las experiencias vividas. Estos testimonios fueron sometidos a varias pruebas de fiabilidad interna (consistencia del testimonio, pruebas de confiabilidad contrastando informaci\u00f3n hist\u00f3rica, coherencia con otros testigos y fuentes, etc.). Para su an\u00e1lisis se estableci\u00f3 una gu\u00eda de items dise\u00f1ada expresamente, basada en los aspectos clave de la psicolog\u00eda de grupo, comportamiento colectivo, obediencia, etc. adem\u00e1s de recoger los datos hist\u00f3ricos que refer\u00edan. Dicha gu\u00eda fue utilizada para hacer un an\u00e1lisis cualitativo de los testimonios recogidos.<\/p>\n<p>10) <i>Documentos de campa\u00f1a y manuales de entrenamiento militar<\/i>. Se analizaron algunos documentos como manuales de interrogatorio utilizados en la formaci\u00f3n de oficiales y servicios de inteligencia (1980), as\u00ed como un Manual de Contrainsurgencia, publicado por el ej\u00e9rcito para uso interno en 1983.<\/p>\n<p>11) Numerosos <i>documentos de la Agencia Central de Inteligencia<\/i> (CIA) y de la Agencia de Inteligencia de Defensa (DIA) de Estados Unidos fueron utilizados para completar la informaci\u00f3n sobre la estructura militar contrainsurgente\u00a0 y los oficiales que participaron en ella, gracias a la desclasificaci\u00f3n de algunos documentos relacionados con Guatemala que fueron procesados por el National Security Archives (NSA) y proporcionados despu\u00e9s al Proyecto REMHI.<\/p>\n<p>Base de datos de los testimonios<\/p>\n<p>Los testimonios fueron analizados por el equipo de codificaci\u00f3n, rellenando una ficha por cada testimonio donde se se\u00f1alaba la presencia o ausencia de los par\u00e1metros indicados en el tesauro. Todos los testimonios fueron metidos en una base de datos utilizando un programa inform\u00e1tico (FoxPro) que permit\u00eda la cuantificaci\u00f3n y el cruce de variables para el an\u00e1lisis cuanti y cualitativo. Los diversos investigadores utilizaron la base de datos como la fuente testimonial para sus an\u00e1lisis. Un equipo de expertos en inform\u00e1tica dise\u00f1\u00f3 expresamente la base de datos y\u00a0 realiz\u00f3, junto con los responsables de investigaci\u00f3n, numerosas pruebas de fiabilidad, funcionamiento y adecuaci\u00f3n de la base de datos al trabajo.<\/p>\n<p>Todos los testimonios fueron introducidos en la base de datos, a partir de las transcripciones textuales realizadas o los res\u00famenes realizados por los entrevistadores. Las entrevistas que ten\u00edan una mayor cantidad y calidad de la informaci\u00f3n fueron transcritas (entrevistas tipo 1). De las entrevistas con menor detalle o concreci\u00f3n de la informaci\u00f3n se utilizaron los res\u00famenes.<\/p>\n<h4>An\u00e1lisis cuantitativo<\/h4>\n<p>Posteriormente se utiliz\u00f3 una matriz de datos en base al programa estad\u00edstico SPSS\u00a0 que nos permiti\u00f3 obtener frecuencias de los diferentes items del tesauro, pero tambi\u00e9n an\u00e1lisis m\u00e1s precisos y complejos como correlaciones estad\u00edsticas para identificar patrones de relaci\u00f3n entre las diferentes variables, regresiones m\u00faltiples y regresiones log\u00edsticas para tratar de establecer la fuerza de dichas correlaciones como variables predictoras. Un resumen de los an\u00e1lisis estad\u00edsticos se encuentra en el siguiente cuadro.<\/p>\n<div>\n<h5><b>Nota t\u00e9cnica sobre los an\u00e1lisis estad\u00edsticos<\/b><\/h5>\n<p>El an\u00e1lisis de datos realizado se bas\u00f3 en el Chi cuadrado y la prueba de asociaci\u00f3n para variables dicot\u00f3micas (el equivalente a los estad\u00edsticos C o Phi\u00a0 del coeficiente de correlaci\u00f3n de Pearson). Dada la gran cantidad de contrastes estad\u00edsticos, para evitar un error de Tipo I, se aplic\u00f3 una correcci\u00f3n de Bonferroni parcial y se consider\u00f3 como significativos los contrastes cuando las probabilidades eran menores de 0,000 (p&lt;0,000) &#8211; recordemos que el punto de corte convencional es 0,05.<\/p>\n<p>Los an\u00e1lisis multivariados realizados fueron el an\u00e1lisis factorial para encontrar dimensiones, la regresi\u00f3n m\u00faltiple\u00a0 para las puntuaciones factoriales derivadas de \u00e9stos an\u00e1lisis, la regresi\u00f3n log\u00edstica cuando los predictores y la variable predecida eran dicot\u00f3micas. Tambi\u00e9n se llevaron a cabo an\u00e1lisis factoriales de segundo orden, para establecer las relaciones entre causas, efectos, formas de afrontamiento y reivindicaciones.<\/p>\n<p>La utilizaci\u00f3n del an\u00e1lisis de componentes principales a partir de correlaciones dicot\u00f3micas Phi puede ser cuestionado. Sin embargo, la comparaci\u00f3n de an\u00e1lisis realizados mediante el m\u00e9todo Prinscal del paquete SPSS, replicando los factores extra\u00eddos mediante an\u00e1lisis factorial, confirmaron los resultados. Lo mismo se puede decir en general: al aplicar m\u00e9todos bi o multivariados de nivel de intervalo los resultados eran totalmente convergentes con los encontrados por los contrastes de tipo categorial.<\/p>\n<\/div>\n<p>Para asegurar la fiabilidad de la informaci\u00f3n y la comparabilidad de los resultados se hicieron varias pruebas entre los datos aportados por los distintos tipos de testimonios (1,2 y 3). Tres mil quinientos testimonios fueron introducidos en la matriz SPSS. Los an\u00e1lisis por separado hechos sobre los testimonios de mayor calidad (tipo1) ofrecieron los mismos indicadores globales que el conjunto de todos los testimonios (tipo 1,2 y 3), por lo que un aumento en el n\u00famero de an\u00e1lisis era irrelevante y cumple todas las\u00a0 bases de la investigaci\u00f3n cient\u00edfica para extrapolar datos generales a partir de muestras espec\u00edficas.<\/p>\n<p>Las correlaciones sirvieron para estructurar los diferentes cap\u00edtulos de la parte testimonial del informe (Tomo I).<\/p>\n<h4>An\u00e1lisis cualitativo<\/h4>\n<p>En base a las conclusiones mostradas por los an\u00e1lisis estad\u00edsticos, se organiz\u00f3 la b\u00fasqueda de informaci\u00f3n cualitativa, obteniendo de la base de datos los cruces de variables necesarios. Se realizaron centenares de cruces de variables entre tipo de hecho, items relativos al impacto psicosocial, zonas geogr\u00e1ficas o variables asociadas a la v\u00edctima. Dichos cruces proporcionaban listados de testimonios que cumpl\u00edan esas caracter\u00edsticas.<\/p>\n<p>Cuando los listados eran muy numerosos, se seleccionaron de forma aleatoria entre 30 y 50 testimonios, seg\u00fan el tama\u00f1o del grupo de testimonios, que fueron le\u00eddos y analizados de forma pormenorizada. En el caso de identificar falta de congruencia entre testimonios o que aparecieran diferentes tendencias se comprobaban las mismas con un n\u00famero mayor de testimonios. Al final del estudio la pr\u00e1ctica totalidad de los testimonios transcritos (un 20% del total, los tipo 1 hab\u00edan sido consultados directamente por los diferentes equipos de investigaci\u00f3n. Adem\u00e1s, un n\u00famero significativo de los testimonios con menor informaci\u00f3n fueron tambi\u00e9n revisados.<\/p>\n<p>La selecci\u00f3n de casos y testimonios incluidos en el informe e corresponde con la tendencia general mostrada por el an\u00e1lisis cualitativo, desechando los casos extremos para evitar dar una idea que exagerase o minimizase las tendencias centrales de los aspectos analizados. S\u00f3lo se incluyeron algunos casos extremos para mostrar el alcance de la violencia o el impacto en los sobrevivientes.<\/p>\n<h4>El caso de las masacres<\/h4>\n<p>El an\u00e1lisis de los testimonios de masacres supuso una dificultad a\u00f1adida al estudio. Los diferentes testimonios que hablaban de masacres en un determinado lugar y a\u00f1o debieron ser sometidos a nuevos estudios adem\u00e1s de los ya se\u00f1alados. Por una parte se elaboraron informes de comparabilidad de los datos y fiabilidad de la informaci\u00f3n referida en muchos de ellos.<\/p>\n<p>Hay que tener en cuenta, por ejemplo, que la memoria puede ser poco fiable para fechas exactas varios a\u00f1os despu\u00e9s del hecho. Adem\u00e1s, en muchos lugares hab\u00edan ocurrido masacres en diferentes momentos y circunstancias. Los informes se\u00f1alaban el grado de consistencia de la informaci\u00f3n recibida (similitudes y diferencias entre los diferentes testimonios recogidos). La informaci\u00f3n consideraba fiable fue aquella que fue confirmada de forma independiente por varios testigos. La informaci\u00f3n dudosa fue desechada. La informaci\u00f3n considerada fiable fue contrastada con algunos estudios de caso encargados a investigadores espec\u00edficos y sin ninguna conexi\u00f3n con las fuentes directas recogidas por el Proyecto REMHI en los testimonios (trabajos sobre el \u00e1rea Ixil y las masacres del Ixc\u00e1n).<\/p>\n<p>Los informes fueron codificados en una matriz espec\u00edfica, que inclu\u00eda varias categor\u00edas, cada una de las cuales ten\u00eda a su vez varios items. Las categor\u00edas eran: 1) situaci\u00f3n anterior a la masacre. 2) n\u00famero de v\u00edctimas 3) tipo de v\u00edctimas (hombres, mujeres, ni\u00f1os, ancianos). 4) modus operandi de los perpetradores (por ejemplo, utilizando listas de nombres,\u00a0 separando hombres de mujeres, encerrando a la gente en un lugar, utilizaci\u00f3n de terror ejemplificante como torturas p\u00fablicas, etc.). 5) impacto de la masacre en los sobrevivientes. 6) consecuencias posteriores (destrucci\u00f3n comunitaria, desplazamiento, etc.). De las 410 masacres identificadas por el Proyecto REMHI se seleccionaron para este an\u00e1lisis 165 masacres representativas de los diferentes a\u00f1os de estudio y regiones del pa\u00eds.<\/p>\n<p>La matriz fue sometida al paquete estad\u00edstico SPSS. Adem\u00e1s de las frecuencias, las relaciones entre los diferentes aspectos de las masacres se obtuvieron mediante an\u00e1lisis factorial exploratorio. Para contrastar la estabilidad de la relaci\u00f3n entre aspectos se utilizaron dos m\u00e9todos, el de Componentes Principales y el de M\u00e1xima Verosimilitud (MV). Las dimensiones que se incluyeron en el informe son aquellas que se encuentran con ambos m\u00e9todos o que se encuentran con el m\u00e1s robusto, el MV. Para estos an\u00e1lisis las diferentes masacres se introdujeron en la matriz y se identificaron con un n\u00famero. El Catedr\u00e1tico de Psicolog\u00eda Social de la Universidad del Pa\u00eds Vasco D. Dar\u00edo P\u00e1ez Rovira, realiz\u00f3 el an\u00e1lisis estad\u00edstico de una manera ciega, sin conocer ninguna de las caracter\u00edsticas de las variables recogidas en la matriz, proporcionando un an\u00e1lisis de frecuencias y correlaciones entre las distintas variables.<\/p>\n<p>Esta metodolog\u00eda trataba de eliminar la influencia del conocimiento previo de testimonios o de la informaci\u00f3n hist\u00f3rica previa, por lo que los datos obtenidos tienen una m\u00e1xima consistencia y confiabilidad. De dicho an\u00e1lisis se establecieron cuatro tipos de masacres que se recogen en el informe<a title=\"\" href=\"#_ftn4\">[4]<\/a>.<\/p>\n<p>Los diferentes datos se completaron posteriormente con el an\u00e1lisis cualitativo de los testimonios y los informes de cada masacre. El an\u00e1lisis de la tendencia por a\u00f1os de todas las masacres registradas muestra que el 38,54% se cometieron en 1982, el 28,54% en 1981 y el 5,12% en 1983. Estos datos se contrastaron posteriormente, mostrando su consistencia, con los datos de la investigaci\u00f3n hist\u00f3rica y las fuentes de organismos internacionales como Amnist\u00eda Internacional consultados.<\/p>\n<p>La descripci\u00f3n del tipo y caracter\u00edsticas de las masacres se contrast\u00f3 tambi\u00e9n con testimonios de victimarios que proporcionaron informaci\u00f3n sobre masacres, secuestros y torturas. El relato de distintos perpetradores (miembros de las Patrullas de Autodefensa Civil, suboficiales u oficiales del ej\u00e9rcito) apoy\u00f3 la consistencia de los an\u00e1lisis previos, describiendo los procedimientos de entrenamiento de la tropa, la educaci\u00f3n en la violencia, la psicolog\u00eda de grupo y los sistemas de control interno que mostraban una pr\u00e1ctica sistem\u00e1tica durante esos a\u00f1os por parte del ej\u00e9rcito de Guatemala.<\/p>\n<h4>Los casos paradigm\u00e1ticos<\/h4>\n<p>El trabajo del REMHI no permiti\u00f3 hacer un seguimiento individualizado de todas las circunstancias concretas de los casos ni investigaci\u00f3n de responsables. Sin embargo se seleccionaron algunos casos considerados como patrones de actuaci\u00f3n respecto a tipos de violencia contra la poblaci\u00f3n civil. En esos casos el Proyecto REMHI llev\u00f3 a cabo una investigaci\u00f3n m\u00e1s profunda, llegando a la convicci\u00f3n de las circunstancias de los hechos y, en algunos casos, de sus autores. Los casos paradigm\u00e1ticos se refirieron a amenazas, secuestros, tortura, desapariciones forzadas, ejecuciones extrajudiciales,\u00a0 prisioneros de guerra, reconversi\u00f3n de la personalidad, c\u00e1rceles clandestinas y preparaci\u00f3n de masacres, y algunos casos espec\u00edficos de la actuaci\u00f3n de la guerrilla (incluidos en los tomos II y III del informe).<\/p>\n<p>Un ejemplo paradigm\u00e1tico es el caso de la investigaci\u00f3n de la masacre de la Embajada de Espa\u00f1a en 1980. La investigaci\u00f3n tom\u00f3 en cuenta y contrast\u00f3 varias fuentes (triangulaci\u00f3n) entre ellas: una entrevista realizada a un informante clave, el Excmo. Sr. Yago Pico de Coa\u00f1a que coordin\u00f3 la investigaci\u00f3n espa\u00f1ola del caso y fue testigo directo de los hechos posteriores a la masacre, junto con el informe oficial del Ministerio de Asuntos Exteriores sobre el caso, la investigaci\u00f3n hemerogr\u00e1fica y documentaci\u00f3n publicada en los medios de comunicaci\u00f3n, as\u00ed como algunos testimonios directos. Todo ello se utiliz\u00f3 para documentar el caso en el Tomo II del Informe.<\/p>\n<h5>Violaciones de los Derechos Humanos y del Derecho Internacional Humanitario<\/h5>\n<p>Para establecer un cuadro de las violaciones de los Derechos Humanos y del Derecho Internacional Humanitario, a partir de los datos recogidos por el proyecto REMHI (Tomo IV del informe) se tuvieron en cuenta los tipos y patrones de violaciones, tal y como se establece en este tipo de estudios, contrast\u00e1ndolas con las leyes y convenios internacionales vigentes relativos a la protecci\u00f3n de derechos humanos y la Constituci\u00f3n guatemalteca.<\/p>\n<p>Dichos patrones fueron: 1) Violaciones del derecho a la vida (incluyendo ejecuciones extrajudiciales, desapariciones forzadas, muertes como resultado de persecuci\u00f3n en la monta\u00f1a, ataques indiscriminados y masacres). 2) Contra el Derecho a la integridad f\u00edsica y psicol\u00f3gica (tortura y tratos crueles inhumanos o degradantes, violaciones sexuales y atentados). 3) Contra el derecho a la seguridad personal (amenazas). 4) Contra el derecho a la libertad personal (detenciones irregulares y convivencia forzada en zonas especiales).<\/p>\n<p>En base a estas categor\u00edas se establecieron las estad\u00edsticas generales de los datos cuantitativos recogidos por el Proyecto REMHI sobre violaciones de los Derechos Humanos y del derecho Internacional Humanitario.<\/p>\n<p>El Proyecto REMHI estableci\u00f3 que en el caso de Guatemala se daban caracter\u00edsticas genocidas debido a las matanzas de miembros de grupos y comunidades enteras, de poblaci\u00f3n no combatiente e incluyendo ni\u00f1os, que fueron frecuentes y se llevaron a cabo en varias regiones del pa\u00eds, aunque no pudo determinar la intencionalidad expresa de eliminar un determinado grupo, dejando dicha consideraci\u00f3n para el trabajo posterior que despu\u00e9s confirm\u00f3 la Comisi\u00f3n para el Esclarecimiento Hist\u00f3rico.<\/p>\n<h5>Valor de la informaci\u00f3n y limitaciones del Informe REMHI<\/h5>\n<p>Debido a que la mayor\u00eda de los testimonios recogidos se refiere a la violencia entre 1979 y 1984, la parte testimonial del informe REMHI ofrece una buena imagen de la din\u00e1mica de la violencia contra la poblaci\u00f3n civil en los a\u00f1os ochenta y especialmente en el \u00e1rea rural. Sin embargo, no se pudieron recoger testimonios en n\u00famero significativo sobre otras \u00e9pocas, como la violencia de los a\u00f1os 60 en las regiones orientales del pa\u00eds ni de la violencia contra los movimientos sociales y bases guerrilleras en los a\u00f1os 70 en la ciudad. Esos l\u00edmites trataron de superarse completando la informaci\u00f3n con otras fuentes y con la investigaci\u00f3n hist\u00f3rica (Tomo III). El informe REMHI ha constituido un estudio \u00fanico, por el tama\u00f1o de la muestra y el an\u00e1lisis de fuentes testimoniales directas, sobre las consecuencias de la violencia en la gente, y algunos mecanismos que la hicieron posible, pero tambi\u00e9n por la dimensi\u00f3n participativa y movilizaci\u00f3n social que supuso.<\/p>\n<p>El informe no pudo contar con gran parte de la informaci\u00f3n de archivos ni planes de campa\u00f1a del ej\u00e9rcito ni parte de la informaci\u00f3n proporcionada por la Agencia Central de Inteligencia desclasificada posteriormente. Otra de las limitaciones del informe es que ofrece una primera aproximaci\u00f3n a la identificaci\u00f3n y an\u00e1lisis jur\u00eddico de los patrones de violaciones de derechos humanos, que se realiz\u00f3 en algunos casos, pero no lleg\u00f3 a sistematizar todo ese trabajo dentro de los plazos de la investigaci\u00f3n. Estas dos limitaciones fueron sin embargo puntos fuertes de la investigaci\u00f3n posterior de la Comisi\u00f3n para el Esclarecimiento Hist\u00f3rico.<\/p>\n<p>&nbsp;<\/p>\n<p>Fdo.<\/p>\n<p>Carlos Mart\u00edn Beristain<\/p>\n<p>Madrid, 16 de octubre de 2000<\/p>\n<p>&nbsp;<\/p>\n<div><br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div>\n<p><a title=\"\" href=\"#_ftnref1\">[1]<\/a>Entre los materiales utilizados se encuentra el dise\u00f1o metodol\u00f3gico de los talleres de capacitaci\u00f3n, un manual para los entrevistadores y una gu\u00eda para la realizaci\u00f3n de talleres. Los materiales se encuentran disponibles para quien est\u00e9 interesado.<\/p>\n<\/div>\n<div>\n<p><a title=\"\" href=\"#_ftnref2\">[2]<\/a>Gu\u00eda de palabras clave que dan acceso a la base de datos y que incluyen tanto aspectos psicosociales de la experiencia de la gente como caracter\u00edsticas del modo de actuaci\u00f3n de las distintas fuerzas responsables.<\/p>\n<\/div>\n<div>\n<p><a title=\"\" href=\"#_ftnref3\">[3]<\/a>Thompson, P. (1978) The voice of the past, Oxford University Press;\u00a0 Halbwachs, M.(1950). La Memoire Collective. Paris. PUF.;<\/p>\n<\/div>\n<div>\n<p><a title=\"\" href=\"#_ftnref4\">[4]<\/a> Se refieren como : a) ataque masivo indiscriminado. b) castigo y terror comunitario c) planificaci\u00f3n de atrocidades y d) terror selectivo. Despu\u00e9s se identific\u00f3 a los autores, resultando 149 causadas por el ej\u00e9rcito y fuerzas paramilitares\u00a0 (91%), 12 por la guerrilla de la URNG (7,3%) y 4 por desconocidos[4]. La mayor parte de las masacres de la guerrilla fueron del tipo d. Alguna del tipo b y una del tipo a. La mayor parte de las masacres del ej\u00e9rcito fueron del tipo a y s\u00f3lo en su caso se dieron del tipo c (incluyendo torturas atroces, violaciones de mujeres, destrucci\u00f3n y saqueo masivos y alto n\u00famero de v\u00edctimas de todas las edades).<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informe elaborado por Carlos Mart\u00edn Beristain, coordinador del Informe Guatemala Nunca M\u00e1s. &nbsp; El Proyecto REMHI En 1995, dos a\u00f1os antes de la firma de los Acuerdos de Paz entre &#8230;<\/p>\n","protected":false},"author":1,"featured_media":247,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acerca-de"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9gm4t-1l","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":91,"url":"https:\/\/www.remhi.org.gt\/portal\/discurso-de-monsenor-juan-gerardi-con-ocasion-de-la-presentacion-del-informe-remhi\/","url_meta":{"origin":83,"position":0},"title":"Discurso de Monse\u00f1or Juan Gerardi con ocasi\u00f3n de la presentaci\u00f3n del informe REMHI","author":"admin","date":"29 enero, 2014","format":false,"excerpt":"Catedral Metropolitana, 24 Abril 1998. El Proyecto REMHI ha sido un esfuerzo que se sit\u00faa dentro de la Pastoral de los Derechos Humanos, que a su vez es parte de la Pastoral Social de la Iglesia: es una misi\u00f3n de servicio al hombre y a la sociedad. Ante los temas\u2026","rel":"","context":"En \u00abAcerca de\u00bb","block_context":{"text":"Acerca de","link":"https:\/\/www.remhi.org.gt\/portal\/category\/acerca-de\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.remhi.org.gt\/portal\/wp-content\/uploads\/2013\/04\/15anios.jpg?fit=503%2C542&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":100,"url":"https:\/\/www.remhi.org.gt\/portal\/comunicado-ceg-conferencia-episcopal-de-guatemala-26abr13\/","url_meta":{"origin":83,"position":1},"title":"Comunicado CEG: Conferencia Episcopal de Guatemala 26\/abr\/13","author":"admin","date":"29 enero, 2014","format":false,"excerpt":"\u201cLA PAZ ESTE CON USTEDES\" (Jn 20,20) Mensaje de la Conferencia Episcopal de Guatemala. Los obispos de Guatemala nos dirigimos a todos los fieles cristianos cat\u00f3licos y a todos los creyentes y hombres y mujeres de buena voluntad. Este tiempo de Pascua nos llama reiteradamente a la esperanza en Cristo\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.remhi.org.gt\/portal\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":180,"url":"https:\/\/www.remhi.org.gt\/portal\/orden-monsenor-gerardi\/","url_meta":{"origin":83,"position":2},"title":"Orden \u00abMonse\u00f1or Gerardi\u00bb","author":"admin","date":"1 diciembre, 2015","format":false,"excerpt":"Bases para Postular Se instaura la \u201cOrden Monse\u00f1or Gerardi a los Derechos Humanos\u201d como un reconocimiento de la Oficina de Derechos Humanos del Arzobispado de Guatemala al trabajo que a favor de los Derechos Humanos, la Memoria Hist\u00f3rica o la preservaci\u00f3n de la Memoria de Monse\u00f1or Juan Gerardi realicen personas\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.remhi.org.gt\/portal\/category\/noticias\/"},"img":{"alt_text":"Orden Gerardi","src":"https:\/\/i0.wp.com\/www.remhi.org.gt\/portal\/wp-content\/uploads\/2015\/12\/ordenGerardi-284x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":139,"url":"https:\/\/www.remhi.org.gt\/portal\/invitacion-a-conversatorio\/","url_meta":{"origin":83,"position":3},"title":"Invitaci\u00f3n a Conversatorio","author":"admin","date":"18 julio, 2014","format":false,"excerpt":"La Oficina de Derechos Humanos del Arzobispado de Guatemala Dentro de las actividades del proyecto \"Por el Derecho a la Memoria\" Tiene el agrado de invitar al Conversatorio \"Archivos y Memoria\" \u00a0 Lugar: Hotel Conquistador. V\u00eda 5 4-68 zona 4, Sal\u00f3n La P\u00e9rgola D\u00eda: Martes 29 de julio, 2014 Hora:\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.remhi.org.gt\/portal\/category\/noticias\/"},"img":{"alt_text":"Invitaci\u00f3n Archivos y memoria","src":"https:\/\/i0.wp.com\/www.remhi.org.gt\/portal\/wp-content\/uploads\/2014\/07\/Invitacio%CC%81n-Archivos-y-memoria-01-300x213.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14,"url":"https:\/\/www.remhi.org.gt\/portal\/presentacion\/","url_meta":{"origin":83,"position":4},"title":"Presentaci\u00f3n","author":"admin","date":"12 enero, 2013","format":false,"excerpt":"Para que todos lo sepan. Palabras de Monse\u00f1or Juan Jos\u00e9 Gerardi\u00a0 que nos empujan a hacer nuestro mejor esfuerzo por dar a conocer la verdad desde las v\u00edctimas quienes con su testimonio nos brindaron la oportunidad de reconstruir una parte de nuestra historia que no queremos repetir. Es por ello\u2026","rel":"","context":"En \u00abInformaci\u00f3n General\u00bb","block_context":{"text":"Informaci\u00f3n General","link":"https:\/\/www.remhi.org.gt\/portal\/category\/informacion-general\/"},"img":{"alt_text":"Logo REMHI","src":"https:\/\/i0.wp.com\/www.remhi.org.gt\/portal\/wp-content\/uploads\/2014\/04\/remhi_loguito1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":89,"url":"https:\/\/www.remhi.org.gt\/portal\/homilia-del-sr-arzobispo-metropolitano-de-santiago-de-guatemala-s-e-mons-oscar-julio-vian-morales-sdb-en-ocasion-del-15-aniversario-del-asesinato-de-mons-juan-jose-gerardi\/","url_meta":{"origin":83,"position":5},"title":"Homil\u00eda del Sr. Arzobispo Metropolitano de Santiago de Guatemala S.E. Mons. Oscar Julio Vian Morales, sdb en ocasio\u0301n del 15 aniversario del asesinato de Mons. Juan Jose\u0301 Gerardi","author":"admin","date":"29 enero, 2014","format":false,"excerpt":"Homili\u0301a del Sr. Arzobispo Metropolitano de Santiago de Guatemala S.E. Mons. Oscar Julio Vian Morales, sdb en ocasio\u0301n de 15 aniversario del asesinato de Mons. Juan Jose\u0301 Gerardi Queridos hermanos y hermanas: \u00a1HOY es pascua para nosotros! \u00a1Jesu\u0301s ha resucitado! En este di\u0301a, 26 de abril, nos reunimos en torno\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.remhi.org.gt\/portal\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.remhi.org.gt\/portal\/wp-content\/uploads\/2013\/04\/archivo_remhi.jpg?fit=384%2C299&ssl=1","_links":{"self":[{"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":5,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":249,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/posts\/83\/revisions\/249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/media\/247"}],"wp:attachment":[{"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.remhi.org.gt\/portal\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}